{"id":4463,"date":"2022-04-14T09:00:19","date_gmt":"2022-04-14T08:00:19","guid":{"rendered":"https:\/\/www.defontemare.com\/product\/testa-tonda-quadro-sottotesta-ma-10x40-inox-a2\/"},"modified":"2026-05-14T10:57:11","modified_gmt":"2026-05-14T09:57:11","slug":"testa-tonda-quadro-sottotesta-ma-10x40-inox-a2","status":"publish","type":"product","link":"https:\/\/www.defontemare.com\/en\/prodotto\/testa-tonda-quadro-sottotesta-ma-10x40-inox-a2\/","title":{"rendered":"TESTA TONDA QUADRO SOTTOTESTA  MA  10X40   INOX A2"},"content":{"rendered":"<p class=\"ef-titolo4\">DIN 603 EN ISO 8677Vite a testa tonda larga con quadro sottotesta senza dado.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIN 603 EN ISO 8677Vite a testa tonda larga con quadro sottotesta senza dado.&nbsp; [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/www.defontemare.com\/en\/prodotto\/testa-tonda-quadro-sottotesta-ma-10x40-inox-a2\/\">Read More&#8230;<span class=\"screen-reader-text\"> from TESTA TONDA QUADRO SOTTOTESTA  MA  10X40   INOX A2<\/span><\/a><\/p>\n","protected":false},"featured_media":29625,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[]},"product_brand":[1019],"product_cat":[110,374],"product_tag":[],"class_list":{"0":"post-4463","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-inox-mare","7":"product_cat-bulloneria-inox","8":"product_cat-tonda-quadro-sottotesta","10":"first","11":"instock","12":"sale","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/product\/4463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/comments?post=4463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/media\/29625"}],"wp:attachment":[{"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/media?parent=4463"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/product_brand?post=4463"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/product_cat?post=4463"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/product_tag?post=4463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}