{"id":2080,"date":"2022-04-14T08:54:58","date_gmt":"2022-04-14T07:54:58","guid":{"rendered":"https:\/\/www.defontemare.com\/product\/jet-popper-williamson-18-cm-col-rw\/"},"modified":"2026-05-14T10:22:25","modified_gmt":"2026-05-14T09:22:25","slug":"jet-popper-williamson-18-cm-col-rw","status":"publish","type":"product","link":"https:\/\/www.defontemare.com\/en\/prodotto\/jet-popper-williamson-18-cm-col-rw\/","title":{"rendered":"JET POPPER WILLIAMSON 18 CM. COL. RW"},"content":{"rendered":"<p class=\"ef-titolo4\">Top fanatici dell&#8217;acqua, pronti per l&#8217;azione. Il Jet Popper di Williamson con la sua grande faccia a coppa ei fori del jet creer\u00e0 un &#8220;pop&#8221; rumoroso e una scia di bolle che far\u00e0 impazzire il pesce. Getta come un proiettile, ma \u00e8 molto stabile sul recupero e facile da lavorare. La costruzione superiore ti consente di combattere il pesce pi\u00f9 grande in circolazione.<\/p>\n<p>La robusta girella collega i lacci ei ganci di linea direttamente all&#8217;esca, consentendo una rotazione perfetta e riducendo la possibilit\u00e0 di un gancio lanciato quando si combatte il pesce. I fori del getto creano un&#8217;enorme bolla.<\/p>\n<p><u>Caratteristiche:<\/u><\/p>\n<p>Costruito in robusti girevoli elimina la leva del pesce agganciato.<\/p>\n<p>Tazza profonda per un effetto &#8220;popping&#8221; extra<\/p>\n<p>I fori del getto creano un&#8217;enorme scia di bolle<\/p>\n<p>Il design unico consente una maggiore distanza di lancio e stabilit\u00e0 al recupero<\/p>\n<p>La pellicola flash all&#8217;interno emette un bagliore luminoso<\/p>\n<p>Anelli elastici ovali ultra forti<\/p>\n<p>Ganci VMC \u00ae Fish Fighter, i treble pi\u00f9 leggeri 6X sul mercato<\/p>\n<p>specifiche tecniche:<\/p>\n<p>Lunghezza &nbsp; &nbsp; &nbsp;&nbsp; 135 mm<\/p>\n<p>Peso &nbsp; &nbsp; &nbsp;&nbsp; 57 g&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Top fanatici dell&#8217;acqua, pronti per l&#8217;azione. Il Jet Popper di Williamson con la sua grande faccia a coppa ei fori [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/www.defontemare.com\/en\/prodotto\/jet-popper-williamson-18-cm-col-rw\/\">Read More&#8230;<span class=\"screen-reader-text\"> from JET POPPER WILLIAMSON 18 CM. COL. RW<\/span><\/a><\/p>\n","protected":false},"featured_media":26974,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[]},"product_brand":[1082],"product_cat":[35,247],"product_tag":[],"class_list":{"0":"post-2080","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-williamson","7":"product_cat-artificiali","8":"product_cat-traina","10":"first","11":"instock","12":"sale","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/product\/2080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/comments?post=2080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/media\/26974"}],"wp:attachment":[{"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/media?parent=2080"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/product_brand?post=2080"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/product_cat?post=2080"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.defontemare.com\/en\/wp-json\/wp\/v2\/product_tag?post=2080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}